{"id":4019,"date":"2019-05-10T09:08:17","date_gmt":"2019-05-10T07:08:17","guid":{"rendered":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3.jpg"},"modified":"2019-05-10T09:08:17","modified_gmt":"2019-05-10T07:08:17","slug":"ulemember3-2","status":"inherit","type":"attachment","link":"https:\/\/barnmissionen.se\/en\/ulemember3-2\/","title":{"rendered":"ULEmember3"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-4019","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"265\" height=\"300\" src=\"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-265x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-265x300.jpg 265w, https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-600x680.jpg 600w, https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-768x870.jpg 768w, https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-904x1024.jpg 904w\" sizes=\"auto, (max-width: 265px) 100vw, 265px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2259,"height":2560,"file":"2019\/05\/ULEmember3-scaled.jpg","filesize":615693,"sizes":{"woocommerce_thumbnail":{"file":"ULEmember3-scaled-300x300.jpg","width":300,"height":300,"filesize":21193,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-scaled-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"ULEmember3-scaled-100x100.jpg","width":100,"height":100,"filesize":4281,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-scaled-100x100.jpg"},"woocommerce_single":{"file":"ULEmember3-scaled-600x680.jpg","width":600,"height":680,"filesize":70379,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-600x680.jpg"},"thumbnail":{"file":"ULEmember3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-150x150.jpg"},"medium":{"file":"ULEmember3-265x300.jpg","width":265,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-265x300.jpg"},"medium_large":{"file":"ULEmember3-768x870.jpg","width":768,"height":870,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-768x870.jpg"},"large":{"file":"ULEmember3-904x1024.jpg","width":904,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-904x1024.jpg"},"shop_catalog":{"file":"ULEmember3-300x300.jpg","width":300,"height":300,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-300x300.jpg"},"shop_single":{"file":"ULEmember3-600x680.jpg","width":600,"height":680,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-600x680.jpg"},"shop_thumbnail":{"file":"ULEmember3-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-100x100.jpg"},"meta-slider-resized-1000x385":{"file":"ULEmember3-1000x385.jpg","width":1000,"height":385,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-1000x385.jpg"},"meta-slider-resized-620x239":{"file":"ULEmember3-620x239.jpg","width":620,"height":239,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-620x239.jpg"},"meta-slider-resized-400x154":{"file":"ULEmember3-400x154.jpg","width":400,"height":154,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-400x154.jpg"},"meta-slider-resized-1000x600":{"file":"ULEmember3-1000x600.jpg","width":1000,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-1000x600.jpg"},"meta-slider-resized-620x372":{"file":"ULEmember3-620x372.jpg","width":620,"height":372,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-620x372.jpg"},"meta-slider-resized-400x240":{"file":"ULEmember3-400x240.jpg","width":400,"height":240,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-400x240.jpg"},"full":{"file":"ULEmember3-scaled.jpg","width":2259,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2019\/05\/ULEmember3-scaled.jpg","_links":{"self":[{"href":"https:\/\/barnmissionen.se\/en\/wp-json\/wp\/v2\/media\/4019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barnmissionen.se\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/barnmissionen.se\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/barnmissionen.se\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/barnmissionen.se\/en\/wp-json\/wp\/v2\/comments?post=4019"}]}}