{"id":6581,"date":"2021-08-10T15:06:40","date_gmt":"2021-08-10T13:06:40","guid":{"rendered":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter.jpg"},"modified":"2021-08-10T15:06:40","modified_gmt":"2021-08-10T13:06:40","slug":"montage-storbandskonserter-2","status":"inherit","type":"attachment","link":"https:\/\/barnmissionen.se\/en\/montage-storbandskonserter-2\/","title":{"rendered":"montage-storbandskonserter"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-6581","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"180\" src=\"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-300x180.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-300x180.jpg 300w, https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-600x360.jpg 600w, https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-768x461.jpg 768w, https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":600,"file":"2021\/08\/montage-storbandskonserter.jpg","filesize":373222,"sizes":{"woocommerce_thumbnail":{"file":"montage-storbandskonserter-300x300.jpg","width":300,"height":300,"filesize":21148,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"montage-storbandskonserter-100x100.jpg","width":100,"height":100,"filesize":3878,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-100x100.jpg"},"woocommerce_single":{"file":"montage-storbandskonserter-600x360.jpg","width":600,"height":360,"filesize":47725,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-600x360.jpg"},"medium":{"file":"montage-storbandskonserter-300x180.jpg","width":300,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-300x180.jpg"},"thumbnail":{"file":"montage-storbandskonserter-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-150x150.jpg"},"medium_large":{"file":"montage-storbandskonserter-768x461.jpg","width":768,"height":461,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-768x461.jpg"},"shop_catalog":{"file":"montage-storbandskonserter-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-300x300.jpg"},"shop_single":{"file":"montage-storbandskonserter-600x360.jpg","width":600,"height":360,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-600x360.jpg"},"shop_thumbnail":{"file":"montage-storbandskonserter-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter-100x100.jpg"},"full":{"file":"montage-storbandskonserter.jpg","width":1000,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/barnmissionen.se\/wp-content\/uploads\/2021\/08\/montage-storbandskonserter.jpg","_links":{"self":[{"href":"https:\/\/barnmissionen.se\/en\/wp-json\/wp\/v2\/media\/6581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barnmissionen.se\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/barnmissionen.se\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/barnmissionen.se\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/barnmissionen.se\/en\/wp-json\/wp\/v2\/comments?post=6581"}]}}